{"id":543,"date":"2014-01-24T00:10:49","date_gmt":"2014-01-24T02:10:49","guid":{"rendered":"http:\/\/www.encontracolombo.com.br\/noticias\/?p=543"},"modified":"2014-01-16T11:11:57","modified_gmt":"2014-01-16T13:11:57","slug":"festa-da-uva-de-colombo-sera-realizada-nos-dias-07-08-e-09-de-fevereiro","status":"publish","type":"post","link":"https:\/\/www.encontracolombo.com.br\/noticias\/festa-da-uva-de-colombo-sera-realizada-nos-dias-07-08-e-09-de-fevereiro\/","title":{"rendered":"Festa da Uva de Colombo ser\u00e1 realizada nos dias 07, 08 e 09 de fevereiro"},"content":{"rendered":"<p>Os dias 07, 08 e 09 de fevereiro ser\u00e3o de muita festa para os visitantes que comparecerem a 51\u00aa edi\u00e7\u00e3o da Festa da Uva de Colombo que neste ano ter\u00e1 como atra\u00e7\u00f5es principais o grupo Negritude Junior, a dupla Cesar Menotti e Fabiano e o cantor Gusttavo Lima. O palco deste evento ser\u00e1 o Parque Municipal da Uva, no Centro de Colombo.<\/p>\n<p>A abertura oficial acontece no dia 07, \u00e0s 18h30, encerrando as atividades do primeiro dia de festa com o show do grupo Negritude Junior. Neste dia, a entrada \u00e9 solid\u00e1ria, ou seja, o visitante ir\u00e1 contribuir com um quilo de alimento n\u00e3o perec\u00edvel. No s\u00e1bado, dia 08, o Parque ser\u00e1 aberto \u00e0 comunidade \u00e0s 12h, seguido durante toda a tarde de shows culturais e a apresenta\u00e7\u00e3o das duplas Cesar Menotti e Fabiano, \u00e0s 20h30 e \u00c1lvaro e Daniel, \u00e0s 22h30.<\/p>\n<p>No domingo, dia 09, os festejos come\u00e7am mais cedo, \u00e0s 10h, com atividades variadas por todos os cantos do Parque que preserva a mata nativa da regi\u00e3o, com 100 mil m\u00b2 de \u00e1rea e espa\u00e7o ao ar livre para passeios e contempla\u00e7\u00e3o da natureza. Neste mesmo local, \u00e0s 21h, se apresenta o cantor Gusttavo Lima para encerrar as atividades do evento que promete reunir mais de 60 mil pessoas nos tr\u00eas dias festa.<\/p>\n<p><strong>Outras atividades<\/strong><\/p>\n<p>Tradicional no Paran\u00e1, o evento vai contar com uma exposi\u00e7\u00e3o de uvas, vinhos, sucos, geleias e conservas como tamb\u00e9m a 13\u00aa Feira da Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os, a Feicom que ter\u00e1 o artesanato local e empresas da regi\u00e3o expondo e comercializando os seus produtos.<\/p>\n<p>A Festa ainda vai contar com uma mostra da gastronomia presente no Circuito Italiano de Turismo Rural que neste ano completa 15 anos. O ponto alto da festa \u00e9 resgatar e manter as tradi\u00e7\u00f5es da cidade como tamb\u00e9m movimentar a economia local, que vai desde a agricultura familiar que \u00e9 a mat\u00e9ria prima da festa at\u00e9 o produto final que s\u00e3o os derivados da fruta, al\u00e9m de trabalhar a quest\u00e3o tur\u00edstica do munic\u00edpio.<\/p>\n<p>O evento \u00e9 uma realiza\u00e7\u00e3o da Prefeitura Municipal de Colombo por meio da Secretaria da Ind\u00fastria, Com\u00e9rcio, Turismo e Cultura.<\/p>\n<p><strong>Servi\u00e7o:<\/strong><\/p>\n<p>O que: 51 Festa da Uva de Colombo<br \/>\nLocal: Parque Municipal da Uva<br \/>\nEndere\u00e7o: Rua Marechal Floriano Peixoto, 8771 Centro<br \/>\nContato: 41-3656.2358 \/ 6181 \/ 2065<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os dias 07, 08 e 09 de fevereiro ser\u00e3o de muita festa para os visitantes que comparecerem a 51\u00aa edi\u00e7\u00e3o da Festa da Uva de Colombo que neste ano ter\u00e1 como atra\u00e7\u00f5es principais o grupo Negritude Junior, a dupla Cesar Menotti e Fabiano e o cantor Gusttavo Lima. O palco deste evento ser\u00e1 o Parque [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-543","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=543"}],"version-history":[{"count":1,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/543\/revisions"}],"predecessor-version":[{"id":544,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/543\/revisions\/544"}],"wp:attachment":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}