{"id":535,"date":"2013-12-06T11:23:09","date_gmt":"2013-12-06T13:23:09","guid":{"rendered":"http:\/\/www.encontracolombo.com.br\/noticias\/?p=535"},"modified":"2013-12-06T11:23:09","modified_gmt":"2013-12-06T13:23:09","slug":"32a-romaria-de-nossa-senhora-imaculada-conceicao-acontece-em-colombo","status":"publish","type":"post","link":"https:\/\/www.encontracolombo.com.br\/noticias\/32a-romaria-de-nossa-senhora-imaculada-conceicao-acontece-em-colombo\/","title":{"rendered":"32\u00aa Romaria de Nossa Senhora Imaculada Concei\u00e7\u00e3o acontece em Colombo"},"content":{"rendered":"<p>Neste dia 08 de dezembro, a partir das 9 horas, acontece a 32\u00aa Romaria de Nossa Senhora Imaculada Concei\u00e7\u00e3o, no Campestre. Neste dia, a p\u00e9, os romeiros partir\u00e3o de Colombo, com a imagem de Nossa Senhora Imaculada Concei\u00e7\u00e3o, com destino ao Campestre.<\/p>\n<p>Com chegada prevista para \u00e0s 10h, toda a caminhada ser\u00e1 acompanhada de ora\u00e7\u00e3o, cantos e mensagens. Ao final da romaria ser\u00e1 realizada uma Santa Missa que ser\u00e1 seguida de um tradicional almo\u00e7o.<\/p>\n<p>O card\u00e1pio ter\u00e1 churrasco, costela, frango, risoto, sopa de bucho, doces e bebidas. Mais informa\u00e7\u00f5es com Vanilda 9184.2307.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste dia 08 de dezembro, a partir das 9 horas, acontece a 32\u00aa Romaria de Nossa Senhora Imaculada Concei\u00e7\u00e3o, no Campestre. Neste dia, a p\u00e9, os romeiros partir\u00e3o de Colombo, com a imagem de Nossa Senhora Imaculada Concei\u00e7\u00e3o, com destino ao Campestre. Com chegada prevista para \u00e0s 10h, toda a caminhada ser\u00e1 acompanhada de ora\u00e7\u00e3o, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-535","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=535"}],"version-history":[{"count":2,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/535\/revisions"}],"predecessor-version":[{"id":537,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/535\/revisions\/537"}],"wp:attachment":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}