{"id":412,"date":"2013-06-04T00:01:10","date_gmt":"2013-06-04T03:01:10","guid":{"rendered":"http:\/\/www.encontracolombo.com.br\/noticias\/?p=412"},"modified":"2013-08-15T17:32:58","modified_gmt":"2013-08-15T20:32:58","slug":"projeto-incentiva-alimentacao-saudavel-em-centro-municipal-de-educacao-infantil-em-colombo","status":"publish","type":"post","link":"https:\/\/www.encontracolombo.com.br\/noticias\/projeto-incentiva-alimentacao-saudavel-em-centro-municipal-de-educacao-infantil-em-colombo\/","title":{"rendered":"Projeto incentiva alimenta\u00e7\u00e3o saud\u00e1vel em centro municipal de educa\u00e7\u00e3o infantil em Colombo"},"content":{"rendered":"<p>Elaborar um trabalho que envolve amor e dedica\u00e7\u00e3o, este foi o principal objetivo da educadora Den\u00edria Garcia de Lima ao idealizar e desenvolver, durante o m\u00eas de maio, o projeto pedag\u00f3gico \u201cN\u00f3s Gostamos de Frutas\u201d, com crian\u00e7as de quatro anos, do Centro Municipal de Educa\u00e7\u00e3o Infantil \u201cPedacinho do C\u00e9u\u201d, na cidade de Colombo.<\/p>\n<p>De acordo com a educadora, o trabalho foi desenvolvido ap\u00f3s observar a resist\u00eancia das crian\u00e7as em comer ou experimentar qualquer tipo de fruta. Ela explica que na realiza\u00e7\u00e3o do projeto foram colocadas em pr\u00e1tica algumas estrat\u00e9gias ensinadas em sala de aula, como a encena\u00e7\u00e3o com est\u00f3rias das frutas, onde os personagens comem e ficam fortes e saud\u00e1veis.<\/p>\n<p>\u201cEnquanto a escola se coloca como espa\u00e7o privilegiado para o dom\u00ednio dos conhecimentos b\u00e1sicos, as institui\u00e7\u00f5es de educa\u00e7\u00e3o infantil, sobretudo, t\u00eam a finalidade de complementar \u00e0 educa\u00e7\u00e3o da fam\u00edlia\u201d, acrescenta.<\/p>\n<p>Den\u00edria acredita que a pr\u00e9-escola tem como uma das principais fun\u00e7\u00f5es incentivar as rela\u00e7\u00f5es educativas vivenciadas no espa\u00e7o de conv\u00edvio coletivo, onde a pr\u00f3pria crian\u00e7a explica, reconta e experimenta o conhecimento adquirido em sala de aula.<\/p>\n<p>Alunos do Pedacinho do C\u00e9u experimentam as frutas<\/p>\n<p>De forma l\u00fadica e interessante, o projeto foi desenvolvido com a intera\u00e7\u00e3o dos alunos, na apresenta\u00e7\u00e3o dos formatos, cores, vitaminas e import\u00e2ncia das frutas. \u201cDescobrir o sabor e a necessidade de se comer frutas aproxima o aluno do real, do poss\u00edvel, da teoria com a pr\u00e1tica, estimulando a aprendizagem\u201d, informa.<\/p>\n<p>Segundo o psic\u00f3logo da prefeitura Andr\u00e9 Baudraz, os principais fatores que contribuem para que as crian\u00e7as, principalmente de dois a oito anos, sejam hostis a frutas e verduras est\u00e3o inseridos na pr\u00f3pria cultura familiar. Ele esclarece que, se esses alimentos n\u00e3o forem introduzidos no cotidiano da crian\u00e7a nos primeiros anos de vida, posteriormente ter\u00e3o dificuldades de aceit\u00e1-los.<\/p>\n<p>De acordo com Baudraz o primeiro passo \u00e9 estimular a alimenta\u00e7\u00e3o saud\u00e1vel e dar exemplos em casa, o segundo \u00e9 evitar que os pequenos comam guloseimas durante os intervalos das refei\u00e7\u00f5es. \u201cSe os pais obrigam os filhos comerem frutas e verduras, mas eles pr\u00f3prios n\u00e3o gostam, com certeza, essas crian\u00e7as v\u00e3o se irritar e v\u00e3o se negar a comer\u201d, afirma.<\/p>\n<p>A coordenadora geral dos Centros Municipais de Educa\u00e7\u00e3o Infantil de Colombo, \u00c1uria Rosa, considera a metodologia utilizada durante o desenvolvimento do projeto adequada para conscientizar crian\u00e7as, mestres e pais. Segundo ela, \u00e9 desenvolvido com intera\u00e7\u00e3o entre alunos, fam\u00edlia, professores, pedagogos e nutricionistas na cidade de Colombo.<\/p>\n<p>De forma l\u00fadica, o projeto \u201cN\u00f3s Gostamos de Frutas\u201d incentiva a alimenta\u00e7\u00e3o saud\u00e1vel<\/p>\n<p>\u00c1uria destacou tamb\u00e9m, a import\u00e2ncia de estimular h\u00e1bitos alimentares e estilos de vida saud\u00e1veis e prevenir o aumento dos casos de obesidade e doen\u00e7as degenerativas na inf\u00e2ncia. \u201cNossa preocupa\u00e7\u00e3o \u00e9 estimular nossas crian\u00e7as a assumir atitudes mais saud\u00e1veis hoje e no futuro\u201d, ponderou.<\/p>\n<p>Teatro<\/p>\n<p>Em meio a um cen\u00e1rio que explora cores e formas, entra em cena e, chama a aten\u00e7\u00e3o dos pequeninos, o personagem \u201cChico\u201d, um menino com apar\u00eancia forte e saud\u00e1vel, obediente que gostava de comer frutas, porque sabia que \u201cs\u00f3 assim cresceria e se tornaria um adulto inteligente e bonito\u201d.<\/p>\n<p>At\u00f4nitos a cada movimento do personagem, as crian\u00e7as eram estimuladas atrav\u00e9s de di\u00e1logos e m\u00fasicas que sugerem h\u00e1bitos de uma alimenta\u00e7\u00e3o saud\u00e1vel. Nas atividades utilizaram as respectivas t\u00e9cnicas como, tinta guache, p\u00f3 de giz, p\u00f3 de gelatina, bolinhas de crepom, l\u00e1pis de cor e colagem de tecido.<\/p>\n<p>\u201cDesenvolver um projeto desperta a criatividade do educando, do professor e do grupo, principalmente quando \u00e9 trabalhado estrategicamente em sala de aula. Atrav\u00e9s do interesse e da alegria dos alunos \u00e9 poss\u00edvel notar o fortalecimento do bem estar de cada um na hora do lanche, comendo as frutas que s\u00e3o servidas todos os dias\u201d, relata a educadora Deliria Garcia.<\/p>\n<p>A aluna Eduarda, do maternal ll, afirmou que antes n\u00e3o gostava de frutas e hoje admite, \u201ccomer fruta \u00e9 importante porque tem vitaminas e o nosso corpo fica bonito e saud\u00e1vel\u201d.<\/p>\n<p><em>Fonte: Prefeitura Municipal de Colombo<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elaborar um trabalho que envolve amor e dedica\u00e7\u00e3o, este foi o principal objetivo da educadora Den\u00edria Garcia de Lima ao idealizar e desenvolver, durante o m\u00eas de maio, o projeto pedag\u00f3gico \u201cN\u00f3s Gostamos de Frutas\u201d, com crian\u00e7as de quatro anos, do Centro Municipal de Educa\u00e7\u00e3o Infantil \u201cPedacinho do C\u00e9u\u201d, na cidade de Colombo. De acordo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,8],"tags":[15],"class_list":["post-412","post","type-post","status-publish","format-standard","hentry","category-noticias","category-servicos","tag-colombo"],"_links":{"self":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=412"}],"version-history":[{"count":3,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/412\/revisions"}],"predecessor-version":[{"id":499,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/412\/revisions\/499"}],"wp:attachment":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}