{"id":375,"date":"2013-04-18T00:01:50","date_gmt":"2013-04-18T03:01:50","guid":{"rendered":"http:\/\/www.encontracolombo.com.br\/noticias\/?p=375"},"modified":"2013-08-15T17:33:07","modified_gmt":"2013-08-15T20:33:07","slug":"prefeitura-de-colombo-cria-forum-permanente-da-crianca-e-do-adolescente","status":"publish","type":"post","link":"https:\/\/www.encontracolombo.com.br\/noticias\/prefeitura-de-colombo-cria-forum-permanente-da-crianca-e-do-adolescente\/","title":{"rendered":"Prefeitura de Colombo cria f\u00f3rum permanente da crian\u00e7a e do adolescente"},"content":{"rendered":"<p>O primeiro F\u00f3rum Permanente de Debate aconteceu no dia 15, na Regional Maracan\u00e3, e teve a inten\u00e7\u00e3o de criar pol\u00edticas p\u00fablicas para melhor atender crian\u00e7as e adolescentes de Colombo. O encontro reuniu o Conselho Municipal de Direitos da Crian\u00e7a de Adolescente, entidades filantr\u00f3picas e servidores municipais que trabalham com a popula\u00e7\u00e3o infanto-juvenil.<\/p>\n<p>\u201cNosso desafio \u00e9 perceber a viol\u00eancia existente na sociedade, na fam\u00edlia e termos consci\u00eancia do nosso papel\u201d, argumenta a secret\u00e1ria da A\u00e7\u00e3o Social e Trabalho, Maria da Silva Souza.<\/p>\n<p>Para chegar neste debate, foi realizado por esta equipe, o diagn\u00f3stico das sete regi\u00f5es que comp\u00f5e a cidade: Centro, \u00c1rea Rural, guia Osasco, Rio Verde, Maracan\u00e3, Guaraituba e Vila Zumbi dos Palmares, com o desafio de desenvolver a\u00e7\u00f5es e projetos em locais estrat\u00e9gicos.<\/p>\n<p>De acordo com a secret\u00e1ria Maria Souza, a principal miss\u00e3o \u00e9 orientar as fam\u00edlias a lidar com os menores e direcion\u00e1-los para cada \u00f3rg\u00e3o competente, em casos especiais. \u201cPretendemos criar projetos que alcancem as \u00e1reas de Educa\u00e7\u00e3o na cidade de Colombo, Sa\u00fade e A\u00e7\u00e3o Social\u201d, relata a secret\u00e1ria.<\/p>\n<p>O F\u00f3rum de Debate Permanente ser\u00e1 realizado na primeira segunda-feira de cada m\u00eas, \u00e0s 8h30, no mini-audit\u00f3rio da Regional Maracan\u00e3. Com a participa\u00e7\u00e3o de entidades filantr\u00f3picas e \u00f3rg\u00e3os municipais e estaduais que est\u00e3o vinculados \u00e1 rede de prote\u00e7\u00e3o \u00e0s crian\u00e7as e adolescentes.<\/p>\n<p>O presidente do Conselho Tutelar, Jeremias Fontoura, citou duas palavras para definir o encontro: Esperan\u00e7a e Expectativa. Segundo ele, o que significam f\u00e9 por algo que ir\u00e1 acontecer e poder\u00e1 mudar a realidade de crian\u00e7as e jovens, na convic\u00e7\u00e3o de serem respons\u00e1veis por um futuro melhor. \u201dNosso objetivo \u00e9 resgatar valores e oferecer oportunidades para as fam\u00edlias\u201d, completou.<\/p>\n<p><em>Fonte: Prefeitura Municipal de Colombo<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O primeiro F\u00f3rum Permanente de Debate aconteceu no dia 15, na Regional Maracan\u00e3, e teve a inten\u00e7\u00e3o de criar pol\u00edticas p\u00fablicas para melhor atender crian\u00e7as e adolescentes de Colombo. O encontro reuniu o Conselho Municipal de Direitos da Crian\u00e7a de Adolescente, entidades filantr\u00f3picas e servidores municipais que trabalham com a popula\u00e7\u00e3o infanto-juvenil. \u201cNosso desafio \u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,8],"tags":[15],"class_list":["post-375","post","type-post","status-publish","format-standard","hentry","category-noticias","category-servicos","tag-colombo"],"_links":{"self":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=375"}],"version-history":[{"count":4,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/375\/revisions"}],"predecessor-version":[{"id":501,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/375\/revisions\/501"}],"wp:attachment":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}