{"id":364,"date":"2013-04-05T00:01:01","date_gmt":"2013-04-05T03:01:01","guid":{"rendered":"http:\/\/www.encontracolombo.com.br\/noticias\/?p=364"},"modified":"2013-08-15T17:32:57","modified_gmt":"2013-08-15T20:32:57","slug":"prefeitura-de-colombo-abre-71-vagas-para-medicos","status":"publish","type":"post","link":"https:\/\/www.encontracolombo.com.br\/noticias\/prefeitura-de-colombo-abre-71-vagas-para-medicos\/","title":{"rendered":"Prefeitura de Colombo abre 71 vagas para m\u00e9dicos"},"content":{"rendered":"<p>A Prefeitura de\u00a0Colombo\u00a0(PR) abriu processo seletivo para 71 vagas para m\u00e9dicos. O contrato \u00e9 pelo prazo de 12 meses, podendo ser prorrogado uma \u00fanica vez, por igual per\u00edodo, at\u00e9 o limite de 2 anos. Ao candidato afrodescendente \u00e9 reservado o percentual de 10% do total de vagas. Os sal\u00e1rios v\u00e3o de R$ 2.798,40 a R$ 9.411,40.<\/p>\n<p>S\u00e3o 10 vagas para m\u00e9dicos para a Estrat\u00e9gia Sa\u00fade da Fam\u00edlia, 47 para m\u00e9dicos plantonistas, 9 para m\u00e9dicos cl\u00ednicos gerais, 3 vagas para m\u00e9dicos psiquiatras, 1 vaga para m\u00e9dico oftalmologista na cidade de Colombo e 1 vaga para m\u00e9dico neurologista.<\/p>\n<p>As inscri\u00e7\u00f5es devem ser feitas at\u00e9 19 de abril, das 8h \u00e0s 12h e das 13h \u00e0s 17h, na Secretaria Municipal de Sa\u00fade, Rua XV de Novembro, n\u00ba 213, 3\u00ba andar, Centro. N\u00e3o ser\u00e1 cobrada taxa de inscri\u00e7\u00e3o.<\/p>\n<p>O processo seletivo ter\u00e1 prova de t\u00edtulos e avalia\u00e7\u00e3o de curr\u00edculo.<\/p>\n<p><em>Fonte: G1<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de\u00a0Colombo\u00a0(PR) abriu processo seletivo para 71 vagas para m\u00e9dicos. O contrato \u00e9 pelo prazo de 12 meses, podendo ser prorrogado uma \u00fanica vez, por igual per\u00edodo, at\u00e9 o limite de 2 anos. Ao candidato afrodescendente \u00e9 reservado o percentual de 10% do total de vagas. Os sal\u00e1rios v\u00e3o de R$ 2.798,40 a R$ [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6,8],"tags":[15],"class_list":["post-364","post","type-post","status-publish","format-standard","hentry","category-empregos","category-noticias","category-servicos","tag-colombo"],"_links":{"self":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=364"}],"version-history":[{"count":2,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/364\/revisions"}],"predecessor-version":[{"id":485,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/364\/revisions\/485"}],"wp:attachment":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}