{"id":338,"date":"2013-03-13T00:01:41","date_gmt":"2013-03-13T03:01:41","guid":{"rendered":"http:\/\/www.encontracolombo.com.br\/noticias\/?p=338"},"modified":"2013-08-15T17:32:54","modified_gmt":"2013-08-15T20:32:54","slug":"havan-abre-vagas-em-colombo","status":"publish","type":"post","link":"https:\/\/www.encontracolombo.com.br\/noticias\/havan-abre-vagas-em-colombo\/","title":{"rendered":"Havan abre vagas em Colombo"},"content":{"rendered":"<p>A Havan Colombo est\u00e1 contratando 200 colaboradores para atuar em diferentes \u00e1reas na nova filial. Se voc\u00ea \u00e9 organizado, motivado e quer crescer profissionalmente, aproveite a oportunidade oferecida pela rede. Envie seu curr\u00edculo para o e-mail: rhcolombo@havan.com.br.<\/p>\n<p>As vagas dispon\u00edveis s\u00e3o para fiscal de loja (seguran\u00e7a na cidade de Colombo), operador de caixa, auxiliar de venda, crediarista, empacotador, auxiliar de dep\u00f3sito, servi\u00e7os gerais, vendedor, estoquista, vitrinista, conferente, promotor de cart\u00e3o e auxiliar de trocas.<\/p>\n<p>Os candidatos precisam estar cursando ou ter conclu\u00eddo o Ensino M\u00e9dio, ter conhecimentos em inform\u00e1tica b\u00e1sica e disponibilidade para trabalhar nos fins de semana. Tamb\u00e9m s\u00e3o indispens\u00e1veis caracter\u00edsticas como gostar de atendimento ao p\u00fablico, comprometimento e dedica\u00e7\u00e3o.<\/p>\n<p>A Havan oferece vale-transporte, vale-alimenta\u00e7\u00e3o e PPR (Programa de Participa\u00e7\u00e3o nos Resultados) como benef\u00edcios. Os sal\u00e1rios s\u00e3o compat\u00edveis com a fun\u00e7\u00e3o.<\/p>\n<p><em>Fonte: Acessa Colombo<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Havan Colombo est\u00e1 contratando 200 colaboradores para atuar em diferentes \u00e1reas na nova filial. Se voc\u00ea \u00e9 organizado, motivado e quer crescer profissionalmente, aproveite a oportunidade oferecida pela rede. Envie seu curr\u00edculo para o e-mail: rhcolombo@havan.com.br. As vagas dispon\u00edveis s\u00e3o para fiscal de loja (seguran\u00e7a na cidade de Colombo), operador de caixa, auxiliar de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6,8],"tags":[15],"class_list":["post-338","post","type-post","status-publish","format-standard","hentry","category-empregos","category-noticias","category-servicos","tag-colombo"],"_links":{"self":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=338"}],"version-history":[{"count":2,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/338\/revisions"}],"predecessor-version":[{"id":467,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/posts\/338\/revisions\/467"}],"wp:attachment":[{"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracolombo.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}